{"id":56166,"date":"2024-08-29T10:28:54","date_gmt":"2024-08-29T14:28:54","guid":{"rendered":"https:\/\/adipro.ca\/fr\/?p=56166"},"modified":"2024-08-29T10:30:24","modified_gmt":"2024-08-29T14:30:24","slug":"angelbird-lancement-aout2024","status":"publish","type":"post","link":"https:\/\/adipro.ca\/fr\/angelbird-lancement-aout2024\/","title":{"rendered":"D\u00e9couvrez le nouveau AV PRO CFexpress Type A SE d&rsquo;ANGELBIRD !"},"content":{"rendered":"<p><span class=\"notion-enable-hover\" data-token-index=\"0\">ANGELBIRD <\/span>\u00e9largit son portefeuille avec une nouvelle version de sa carte m\u00e9moire de type A tr\u00e8s attendue !<\/p>\n<p>Voici la carte <strong><span class=\"notion-enable-hover\" data-token-index=\"2\"><a href=\"https:\/\/www.angelbird.com\/prod\/av-pro-cfexpress-a-se-3448\/?category=317\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Angelbird AV PRO CFexpress Type A SE<\/a><\/span><\/strong>, elles sont id\u00e9ales pour les appareils photo des s\u00e9ries Sony Alpha et FX tels que Sony \u03b11, Sony \u03b19 III, Sony \u03b17 IV, Sony \u03b17R V, Sony \u03b17 S III, Sony FX3, Sony FX30 et Sony FX6. Ces cartes d&rsquo;entr\u00e9e de gamme sont con\u00e7ues pour la polyvalence des projets et les performances \u00e0 grande vitesse et maintiennent la vitesse essentielle pour les photos RAW jusqu&rsquo;\u00e0 8K et l&rsquo;enregistrement vid\u00e9o 8K. Capturez de longues photos \u00e0 haut d\u00e9bit de donn\u00e9es en r\u00e9solution 4K+, des contenus vid\u00e9o fluides et b\u00e9n\u00e9ficiez d&rsquo;une prise en charge \u00e9tendue de la m\u00e9moire tampon pour la photographie en rafale.<\/p>\n<p>Gr\u00e2ce \u00e0 la technologie Stable Stream\u2122, une vitesse d&rsquo;\u00e9criture soutenue ininterrompue de 650 Mo\/s garantit des performances et une qualit\u00e9 d&rsquo;image constantes. Ces cartes sont con\u00e7ues pour r\u00e9sister \u00e0 des conditions extr\u00eames et offrent un stockage m\u00e9dia fiable et de haute qualit\u00e9 pour explorer les fonctionnalit\u00e9s avanc\u00e9es des appareils photo Sony.<\/p>\n<p><!-- notionvc: f3c0a54e-8357-4254-b98d-1c6f387a31e5 --><\/p>\n<p><a href=\"https:\/\/adipro.ca\/wp-content\/uploads\/2024\/08\/AV-PRO-CFexpress-A-SE_160GB-and-330GB_02_Web_3000x3000_20240813.png\"><img decoding=\"async\" class=\"wp-image-56161 aligncenter\" src=\"https:\/\/adipro.ca\/wp-content\/uploads\/2024\/08\/AV-PRO-CFexpress-A-SE_160GB-and-330GB_02_Web_3000x3000_20240813.png\" alt=\"AV-PRO-CFexpress-A-SE_160GB-and-330GB_02_Web_3000x3000_20240813\" width=\"223\" height=\"167\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANGELBIRD \u00e9largit son portefeuille avec une nouvelle version de sa carte m\u00e9moire de type A tr\u00e8s attendue ! Voici la carte Angelbird AV PRO CFexpress Type A SE, elles sont id\u00e9ales pour les appareils photo des s\u00e9ries Sony Alpha et FX tels que Sony \u03b11, Sony \u03b19 III, Sony \u03b17 IV, Sony \u03b17R V, Sony [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":63899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[55,56],"tags":[242,219,245],"brand-tag":[],"class_list":["post-56166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio-pro-fr","category-audio-video-mobile-fr","tag-adi-pro-2","tag-adi-pro","tag-angelbird"],"acf":[],"_links":{"self":[{"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/posts\/56166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/comments?post=56166"}],"version-history":[{"count":0,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/posts\/56166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/media\/63899"}],"wp:attachment":[{"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/media?parent=56166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/categories?post=56166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/tags?post=56166"},{"taxonomy":"brand-tag","embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/brand-tag?post=56166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}