{"id":60477,"date":"2025-09-30T09:20:13","date_gmt":"2025-09-30T13:20:13","guid":{"rendered":"https:\/\/adipro.ca\/fr\/?p=60477"},"modified":"2026-04-15T14:52:15","modified_gmt":"2026-04-15T18:52:15","slug":"nouvelle-marque-distribuee-kondor-blue","status":"publish","type":"post","link":"https:\/\/adipro.ca\/fr\/nouvelle-marque-distribuee-kondor-blue\/","title":{"rendered":"Nouvelle marque distribu\u00e9e &#8211; KONDOR BLUE"},"content":{"rendered":"<p>Nous sommes heureux d\u2019annoncer qu\u2019<strong>adipro.ca\/ est d\u00e9sormais\u00a0<\/strong><strong>le distributeur officiel de Kondor Blue au Canada!<\/strong><\/p>\n<p><strong>Kondor Blue \u2013 Con\u00e7u par des cr\u00e9atifs, pour des cr\u00e9atifs<\/strong><\/p>\n<p>Kondor Blue est une marque d\u2019accessoires de tournage cr\u00e9\u00e9e par des cin\u00e9astes qui connaissent les exigences du plateau. Leur philosophie est simple : <strong>fonctionnalit\u00e9, durabilit\u00e9 et excellence du design<\/strong>. Chaque produit r\u00e9pond \u00e0 des besoins concrets de production, r\u00e9siste \u00e0 une utilisation professionnelle quotidienne et affiche une esth\u00e9tique \u00e9l\u00e9gante qui le distingue.<\/p>\n<p>La gamme comprend des <strong>cages et rigs cam\u00e9ra<\/strong> usin\u00e9s avec pr\u00e9cision pour Canon, Sony, Blackmagic, Panasonic et plus encore, ainsi que des <strong>accessoires de rigging<\/strong> tels que poign\u00e9es, clamps, tiges et syst\u00e8mes \u00e0 d\u00e9gagement rapide pour une reconfiguration rapide et fiable. Kondor Blue se distingue aussi avec ses <strong>c\u00e2bles professionnels<\/strong> \u2014 tress\u00e9s, spiral\u00e9s ou \u00e0 angle droit (HDMI, SDI, D-Tap, USB-C) \u2014 con\u00e7us pour une durabilit\u00e9 maximale et propos\u00e9s en plusieurs couleurs pour une identification facile. Leurs <strong>solutions d\u2019alimentation<\/strong> \u2014 plaques V-Mount, adaptateurs et syst\u00e8mes de c\u00e2blage \u2014 permettent d\u2019alimenter un ensemble complet \u00e0 partir d\u2019une seule batterie. Les <strong>outils de montage<\/strong> et le <strong>mat\u00e9riel sp\u00e9cialis\u00e9<\/strong> comme les clap de production compl\u00e8tent le catalogue.<\/p>\n<p>Ce qui distingue vraiment Kondor Blue, c\u2019est la confiance qu\u2019ils offrent aux cr\u00e9ateurs. Appuy\u00e9s par une <strong>garantie \u00e0 vie<\/strong>, tous les accessoires sont con\u00e7us pour durer et soutenus par une \u00e9quipe qui comprend l\u2019urgence des tournages professionnels.<\/p>\n<p>Pour explorer la gamme des produits Kondor Blue, S.V.P. visiter\u00a0<a href=\"https:\/\/kondorblue.com\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/kondorblue.com\/<\/a><\/p>\n<p>Pour devenir revendeur, S.V.P. nous appeler au 1-866-449-8177 pour \u00eatre mis en communication avec votre repr\u00e9sentant.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes heureux d\u2019annoncer qu\u2019adipro.ca\/ est d\u00e9sormais\u00a0le distributeur officiel de Kondor Blue au Canada! Kondor Blue \u2013 Con\u00e7u par des cr\u00e9atifs, pour des cr\u00e9atifs Kondor Blue est une marque d\u2019accessoires de tournage cr\u00e9\u00e9e par des cin\u00e9astes qui connaissent les exigences du plateau. Leur philosophie est simple : fonctionnalit\u00e9, durabilit\u00e9 et excellence du design. Chaque produit [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56,55],"tags":[242,219],"brand-tag":[],"class_list":["post-60477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio-video-mobile-fr","category-audio-pro-fr","tag-adi-pro-2","tag-adi-pro"],"acf":[],"_links":{"self":[{"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/posts\/60477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/comments?post=60477"}],"version-history":[{"count":0,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/posts\/60477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/media\/66106"}],"wp:attachment":[{"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/media?parent=60477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/categories?post=60477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/tags?post=60477"},{"taxonomy":"brand-tag","embeddable":true,"href":"https:\/\/adipro.ca\/fr\/wp-json\/wp\/v2\/brand-tag?post=60477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}